{"id":85153,"date":"2025-12-15T19:48:19","date_gmt":"2025-12-16T01:48:19","guid":{"rendered":"https:\/\/nitu.mx\/?p=85153"},"modified":"2025-12-15T19:48:20","modified_gmt":"2025-12-16T01:48:20","slug":"wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark","status":"publish","type":"post","link":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/","title":{"rendered":"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark"},"content":{"rendered":"\n<p>Wyndham Hotels &amp; Resorts, la compa\u00f1\u00eda de franquicias hoteleras m\u00e1s grande del mundo con aproximadamente 8,300 hoteles en cerca de 100 pa\u00edses, contin\u00faa expandiendo su presencia en destinos emblem\u00e1ticos de M\u00e9xico con la apertura del Hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark Collection by Wyndham.<br><br>La celebraci\u00f3n oficial por la inauguraci\u00f3n del Hotel Ex Hacienda de Chautla, Trademark Collection by Wyndham, se llev\u00f3 a cabo el pasado 21 de noviembre, representando un hito para la presencia de la compa\u00f1\u00eda en el estado de Puebla, con lo que a su vez, refuerza el crecimiento estrat\u00e9gico de la marca en M\u00e9xico.<br><br>El evento cont\u00f3 con la participaci\u00f3n de Carla L\u00f3pez-Malo Villal\u00f3n, secretaria de Turismo del Estado de Puebla; \u00a0Roberto Scharrer, Development Manager de Wyndham Hotels &amp; Resorts; as\u00ed como del propietario del hotel y de su equipo.<br><br>Durante la ceremonia se llev\u00f3 a cabo el tradicional corte de list\u00f3n, marcando el inicio formal de operaciones bajo la marca.<br><br>El Hotel Ex Hacienda Chautla Puebla, Trademark Collection by Wyndham, fue desarrollado para ofrecer una experiencia de hospedaje que combina autenticidad, confort y un dise\u00f1o con car\u00e1cter propio, en un entorno que invita al descanso y a la conexi\u00f3n con la naturaleza.<br><br>Ubicado a orillas del lago que rodea la Ex Hacienda de Chautla, uno de los recintos hist\u00f3ricos m\u00e1s representativos del estado, el hotel permite a sus visitantes recorrer sus jardines, senderos y espacios restaurados, adem\u00e1s de disfrutar actividades al aire libre, lo que lo convierte en un espacio ideal para bodas destino, convenciones y actividades de\u00a0team building.<br><br>La propiedad cuenta con un total de 90 habitaciones, de las cuales 29 ya est\u00e1n disponibles para reservar. El resto se habilitar\u00e1 de manera progresiva conforme avance su proceso de remodelaci\u00f3n, con el objetivo de ampliar la oferta para sus hu\u00e9spedes.<br><br>\u201cEste proyecto representa una nueva era para la Ex-Hacienda de Chautla y para el turismo de Puebla. Es un honor recibir a quienes hacen posible que la historia y la hospitalidad se unan en este espacio \u00fanico\u201d, coment\u00f3\u00a0Maritza P\u00e9rez, direcci\u00f3n de Operaciones Hoteleras Corporativo A5.<\/p>\n\n\n\n<p>\u201cLa apertura del Hotel Ex Hacienda Chautla Puebla, bajo la marca Trademark by Wyndham, refuerza nuestro compromiso de seguir impulsando el crecimiento de Wyndham Hotels &amp; Resorts en M\u00e9xico con proyectos que celebran la riqueza hist\u00f3rica y natural del pa\u00eds. Hoy nos enorgullece ver esta marca en un destino tan emblem\u00e1tico como Puebla, donde los viajeros podr\u00e1n disfrutar una experiencia \u00fanica que combina historia, naturaleza y dise\u00f1o para ofrecer una estancia aut\u00e9ntica, confortable y memorable\u201d, se\u00f1al\u00f3 Roberto Scharrer, Manager, Development, M\u00e9xico, Wyndham Hotels &amp; Resorts.<\/p>\n\n\n\n<p>Los hoteles bajo la marca\u00a0Trademark Collection by Wyndham, se distinguen por ofrecer a los hu\u00e9spedes la oportunidad de vivir cada destino a su manera. As\u00ed como no hay dos viajeros iguales, cada hotel de Trademark Collection refleja un car\u00e1cter propio y brinda experiencias aut\u00e9nticas y memorables.<br><br><strong>Comodidades dise\u00f1adas para una estad\u00eda memorable<\/strong><br>La arquitectura del hotel, de estilo hacienda, conserva su estructura colonial e incorpora comodidades modernas, tales como gimnasio, amplias \u00e1reas verdes y una terraza con vistas privilegiadas. Adem\u00e1s, en etapas posteriores de la remodelaci\u00f3n, se incluir\u00e1 una piscina techada y climatizada; as\u00ed como spa y actividades Wellness.<br><br>Su ubicaci\u00f3n permite acceder f\u00e1cilmente al emblem\u00e1tico castillo, su museo y los senderos que recorren la finca. Asimismo, se sit\u00faa a 27 kil\u00f3metros del Aeropuerto Internacional de Puebla.<br><br>Los hu\u00e9spedes pueden iniciar el d\u00eda con un desayuno de cocina mexicana e internacional de autor, preparado con ingredientes t\u00edpicos de la regi\u00f3n, en el restaurante \u201cMagueyana\u201d, abierto todo el d\u00eda; o bien, disfrutar del servicio de habitaciones. El hotel complementa la experiencia con un bar, jardines y espacios ideales para la relajaci\u00f3n y un elegante sal\u00f3n para eventos sociales y corporativos, rodeado de un entorno natural que realza celebraciones y reuniones especiales.<br><br>Todas las habitaciones son para no fumadores y est\u00e1n equipadas con WiFi gratuito, balc\u00f3n, televisi\u00f3n de pantalla plana, escritorio, cafetera\/tetera, caja fuerte para laptop, amenidades de ba\u00f1o, secador de pelo, aire acondicionado y agua embotellada. La recepci\u00f3n opera las 24 horas para atender cualquier solicitud. (<a href=\"https:\/\/nitu.mx\/index.php\/2025\/12\/11\/wyndham-latamc-potencia-su-crecimiento-en-el-segmento-leisure-con-la-participacion-en-fitur-2026\/\">Wyndham LATAMC potencia su crecimiento en el segmento leisure con la participaci\u00f3n en FITUR 2026<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wyndham Hotels &amp; Resorts, la compa\u00f1\u00eda de franquicias hoteleras m\u00e1s grande del mundo con aproximadamente 8,300 hoteles en cerca de 100 pa\u00edses, contin\u00faa expandiendo su presencia en destinos emblem\u00e1ticos de M\u00e9xico con la apertura del Hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark Collection by Wyndham. La celebraci\u00f3n oficial por la inauguraci\u00f3n del Hotel [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":85156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[27894,62,19955,10533],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark - Nitu - Noticias de la Industria Turistica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark - Nitu - Noticias de la Industria Turistica\" \/>\n<meta name=\"twitter:description\" content=\"Wyndham Hotels &amp; Resorts, la compa\u00f1\u00eda de franquicias hoteleras m\u00e1s grande del mundo con aproximadamente 8,300 hoteles en cerca de 100 pa\u00edses, contin\u00faa expandiendo su presencia en destinos emblem\u00e1ticos de M\u00e9xico con la apertura del Hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark Collection by Wyndham. La celebraci\u00f3n oficial por la inauguraci\u00f3n del Hotel [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@NITUmx\" \/>\n<meta name=\"twitter:site\" content=\"@Arturo_Medina_G\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b\"},\"headline\":\"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark\",\"datePublished\":\"2025-12-16T01:48:19+00:00\",\"dateModified\":\"2025-12-16T01:48:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/\"},\"wordCount\":756,\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg\",\"keywords\":[\"Ex Hacienda Chautla\",\"Puebla\",\"Trademark Collection\",\"Wyndham Hotels &amp; Resorts\"],\"articleSection\":[\"Hoteles\"],\"inLanguage\":\"es-MX\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/\",\"url\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/\",\"name\":\"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark - Nitu - Noticias de la Industria Turistica\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg\",\"datePublished\":\"2025-12-16T01:48:19+00:00\",\"dateModified\":\"2025-12-16T01:48:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Wyndham Ex hacienda Chautla Puebla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/nitu.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nitu.mx\/#website\",\"url\":\"https:\/\/nitu.mx\/\",\"name\":\"Nitu - Noticias de la Industria Turistica\",\"description\":\"Noticias de la Industria Turistica\",\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"alternateName\":\"Noticias de la Industria Turistica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nitu.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\",\"name\":\"Arturo Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"width\":90,\"height\":90,\"caption\":\"Arturo Medina\"},\"logo\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\"},\"description\":\"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx\",\"sameAs\":[\"https:\/\/nitu.mx\",\"https:\/\/www.facebook.com\/NITUmx\/\",\"medinacancun\",\"https:\/\/twitter.com\/@Arturo_Medina_G\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\/\/nitu.mx\/index.php\/author\/redaccion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark - Nitu - Noticias de la Industria Turistica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/","twitter_card":"summary_large_image","twitter_title":"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark - Nitu - Noticias de la Industria Turistica","twitter_description":"Wyndham Hotels &amp; Resorts, la compa\u00f1\u00eda de franquicias hoteleras m\u00e1s grande del mundo con aproximadamente 8,300 hoteles en cerca de 100 pa\u00edses, contin\u00faa expandiendo su presencia en destinos emblem\u00e1ticos de M\u00e9xico con la apertura del Hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark Collection by Wyndham. La celebraci\u00f3n oficial por la inauguraci\u00f3n del Hotel [&hellip;]","twitter_image":"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg","twitter_creator":"@NITUmx","twitter_site":"@Arturo_Medina_G","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#article","isPartOf":{"@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b"},"headline":"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark","datePublished":"2025-12-16T01:48:19+00:00","dateModified":"2025-12-16T01:48:20+00:00","mainEntityOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/"},"wordCount":756,"publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg","keywords":["Ex Hacienda Chautla","Puebla","Trademark Collection","Wyndham Hotels &amp; Resorts"],"articleSection":["Hoteles"],"inLanguage":"es-MX"},{"@type":"WebPage","@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/","url":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/","name":"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark - Nitu - Noticias de la Industria Turistica","isPartOf":{"@id":"https:\/\/nitu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg","datePublished":"2025-12-16T01:48:19+00:00","dateModified":"2025-12-16T01:48:20+00:00","breadcrumb":{"@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#primaryimage","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2025\/12\/Wyndham-Ex-hacienda-Chautla-Puebla.jpg","width":1200,"height":675,"caption":"Wyndham Ex hacienda Chautla Puebla"},{"@type":"BreadcrumbList","@id":"https:\/\/nitu.mx\/index.php\/2025\/12\/15\/wyndham-abre-el-hotel-ex-hacienda-chautla-puebla-bajo-su-marca-trademark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/nitu.mx\/"},{"@type":"ListItem","position":2,"name":"Wyndham abre el hotel Ex Hacienda Chautla Puebla, bajo su marca Trademark"}]},{"@type":"WebSite","@id":"https:\/\/nitu.mx\/#website","url":"https:\/\/nitu.mx\/","name":"Nitu - Noticias de la Industria Turistica","description":"Noticias de la Industria Turistica","publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"alternateName":"Noticias de la Industria Turistica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitu.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":["Person","Organization"],"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc","name":"Arturo Medina","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","width":90,"height":90,"caption":"Arturo Medina"},"logo":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/"},"description":"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx","sameAs":["https:\/\/nitu.mx","https:\/\/www.facebook.com\/NITUmx\/","medinacancun","https:\/\/twitter.com\/@Arturo_Medina_G"]},{"@type":"Person","@id":"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/nitu.mx\/index.php\/author\/redaccion\/"}]}},"views":829,"_links":{"self":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/85153"}],"collection":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=85153"}],"version-history":[{"count":1,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/85153\/revisions"}],"predecessor-version":[{"id":85155,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/85153\/revisions\/85155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media\/85156"}],"wp:attachment":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=85153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=85153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=85153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}