{"id":61366,"date":"2022-09-14T23:51:28","date_gmt":"2022-09-15T04:51:28","guid":{"rendered":"https:\/\/www.dev.nitu.mx\/?p=61366"},"modified":"2022-09-15T00:26:38","modified_gmt":"2022-09-15T05:26:38","slug":"viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc","status":"publish","type":"post","link":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/","title":{"rendered":"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC"},"content":{"rendered":"<p>Viva Aerobus present\u00f3\u00a0HSBC VIVA,\u00a0la primera tarjeta de cr\u00e9dito de marca compartida de esta instituci\u00f3n bancaria, dise\u00f1ada para llevar la experiencia de viaje de los pasajeros al siguiente nivel con promociones exclusivas.<\/p>\n<p>De acuerdo con la aerol\u00ednea y la instituci\u00f3n bancaria, adem\u00e1s de las tarifas bajas con esta nueva tarjeta de cr\u00e9dito, brindan a los pasajeros beneficios \u00fanicos y numerosas facilidades para que volar sea todav\u00eda m\u00e1s atractivo, sencillo y al alcance de m\u00e1s personas, contando con el respaldo de HSBC y Mastercard.<\/p>\n<p>Entre los beneficios de\u00a0HSBC VIVA\u00a0destaca que es la \u00fanica forma de pago que ofrece, de manera permanente, meses sin intereses para la adquisici\u00f3n de boletos de avi\u00f3n con Viva Aerobus.<\/p>\n<p>A ello se suma otra serie de ventajas como acceso prioritario en el abordaje y accesos a las salas de Mastercard en el Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM).<\/p>\n<p>Los tarjetahabientes tambi\u00e9n cuentan con beneficios adicionales dentro del programa de lealtad y recompensas Doters, recientemente lanzado por Viva Aerobus.<\/p>\n<p>Al ser miembro de este programa y utilizar\u00a0HSBC VIVA,\u00a0dependiendo de las compras que se realicen, se tiene la posibilidad de obtener entre uno y hasta cuatro vuelos gratis como recompensa durante el primer a\u00f1o de uso de la tarjeta.<\/p>\n<p>Esto se a\u00f1ade a los Puntos Doters de bienvenida y aniversario; as\u00ed como una mayor acumulaci\u00f3n de puntos en cada compra que hacen en Viva Aerobus para que despu\u00e9s puedan canjearlos por vuelos, servicios adicionales y muchos productos m\u00e1s.<\/p>\n<p>\u201cLos viajes representan el 8% del consumo que se realiza con tarjetas de cr\u00e9dito en el pa\u00eds. Por ello, esta alianza con Viva Aerobus es estrat\u00e9gica, al ser la segunda aerol\u00ednea m\u00e1s grande del mercado dom\u00e9stico en M\u00e9xico, con m\u00e1s de 15 millones de pasajeros en 2021\u201d, dijo Jorge Arce, presidente y director general de HSBC M\u00e9xico.<\/p>\n<p>\u201cAl trabajar en equipo, podemos sumar y apoyar el inter\u00e9s de las personas por viajar y vivir nuevas experiencias, en un a\u00f1o en el que tanto el consumo con tarjetas como los viajes a\u00e9reos se est\u00e1n reactivando\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La tarjeta cuenta con dos modalidades:\u00a0HSBC VIVA\u00a0y\u00a0HSBC VIVA PLUS,\u00a0dependiendo del perfil de cada usuario.\u00a0Con la primera, aunado a los beneficios ya mencionados, los viajeros pueden transportar, una vez al a\u00f1o, una maleta documentada de 15 kg sin costo; contar con un seguro de protecci\u00f3n de compras de Mastercard y obtener cuatro accesos a la sala Elite Lounge de Mastercard en el AICM.<\/p>\n<p>Mientras que con la segunda, los clientes disponen de equipaje en cabina (10 kg) y documentado (15 kg) sin costo; selecci\u00f3n gratuita de asiento VIP; seguro Platinum Mastercard; 10 accesos al Lounge Key al a\u00f1o y entrada ilimitada a la sala Elite Lounge de Mastercard en el AICM.<\/p>\n<p>\u201cDesde hace 16 a\u00f1os, Viva Aerobus ha revolucionado la manera de volar gracias a su modelo de negocios de ultra bajo costo, poniendo al alcance de m\u00e1s personas la posibilidad de viajar en avi\u00f3n. Y, hoy, de la mano de HSBC, una instituci\u00f3n financiera l\u00edder y presencia internacional, reforzamos este compromiso con una tarjeta de cr\u00e9dito que facilita, a\u00fan m\u00e1s, acceder al transporte a\u00e9reo y con un valor a\u00f1adido para que todos nuestros pasajeros disfruten al m\u00e1ximo cada uno de sus viajes con grandes beneficios, precios bajos, vuelos directos y la flota m\u00e1s nueva de M\u00e9xico\u201d, detall\u00f3 Juan Carlos Zuazua, director general de Viva Aerobus.<\/p>\n<p>A partir del 19 de septiembre, HSBC VIVA podr\u00e1 solicitarse a trav\u00e9s de los sitios web de Viva Aerobus y HSBC M\u00e9xico, as\u00ed como en las sucursales bancarias.\u00a0<a title=\"Mercado dom\u00e9stico impulsa crecimiento de Viva Aerobus en agosto\" href=\"https:\/\/www.dev.nitu.mx\/index.php\/2022\/09\/07\/mercado-domestico-impulsa-crecimiento-de-viva-aerobus-en-agosto\/\" rel=\"bookmark\">(Mercado dom\u00e9stico impulsa crecimiento de Viva Aerobus en agosto<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viva Aerobus present\u00f3\u00a0HSBC VIVA,\u00a0la primera tarjeta de cr\u00e9dito de marca compartida de esta instituci\u00f3n bancaria, dise\u00f1ada para llevar la experiencia de viaje de los pasajeros al siguiente nivel con promociones exclusivas. De acuerdo con la aerol\u00ednea y la instituci\u00f3n bancaria, adem\u00e1s de las tarifas bajas con esta nueva tarjeta de cr\u00e9dito, brindan a los pasajeros [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":61370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[6187,23584,295,23583,2102],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC - Nitu - Noticias de la Industria Turistica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC - Nitu - Noticias de la Industria Turistica\" \/>\n<meta name=\"twitter:description\" content=\"Viva Aerobus present\u00f3\u00a0HSBC VIVA,\u00a0la primera tarjeta de cr\u00e9dito de marca compartida de esta instituci\u00f3n bancaria, dise\u00f1ada para llevar la experiencia de viaje de los pasajeros al siguiente nivel con promociones exclusivas. De acuerdo con la aerol\u00ednea y la instituci\u00f3n bancaria, adem\u00e1s de las tarifas bajas con esta nueva tarjeta de cr\u00e9dito, brindan a los pasajeros [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@NITUmx\" \/>\n<meta name=\"twitter:site\" content=\"@Arturo_Medina_G\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b\"},\"headline\":\"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC\",\"datePublished\":\"2022-09-15T04:51:28+00:00\",\"dateModified\":\"2022-09-15T05:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/\"},\"wordCount\":656,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg\",\"keywords\":[\"HSBC\",\"HSBC VIVA\",\"Juan Carlos Zuazua\",\"tarjeta de cr\u00e9dito\",\"Viva Aerobus\"],\"articleSection\":[\"Aerol\u00edneas\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/\",\"url\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/\",\"name\":\"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC - Nitu - Noticias de la Industria Turistica\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg\",\"datePublished\":\"2022-09-15T04:51:28+00:00\",\"dateModified\":\"2022-09-15T05:26:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg\",\"width\":1200,\"height\":675,\"caption\":\"Viva Aerobus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/nitu.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nitu.mx\/#website\",\"url\":\"https:\/\/nitu.mx\/\",\"name\":\"Nitu - Noticias de la Industria Turistica\",\"description\":\"Noticias de la Industria Turistica\",\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"alternateName\":\"Noticias de la Industria Turistica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nitu.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\",\"name\":\"Arturo Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"width\":90,\"height\":90,\"caption\":\"Arturo Medina\"},\"logo\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\"},\"description\":\"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx\",\"sameAs\":[\"https:\/\/nitu.mx\",\"https:\/\/www.facebook.com\/NITUmx\/\",\"medinacancun\",\"https:\/\/twitter.com\/@Arturo_Medina_G\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\/\/nitu.mx\/index.php\/author\/redaccion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC - Nitu - Noticias de la Industria Turistica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/","twitter_card":"summary_large_image","twitter_title":"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC - Nitu - Noticias de la Industria Turistica","twitter_description":"Viva Aerobus present\u00f3\u00a0HSBC VIVA,\u00a0la primera tarjeta de cr\u00e9dito de marca compartida de esta instituci\u00f3n bancaria, dise\u00f1ada para llevar la experiencia de viaje de los pasajeros al siguiente nivel con promociones exclusivas. De acuerdo con la aerol\u00ednea y la instituci\u00f3n bancaria, adem\u00e1s de las tarifas bajas con esta nueva tarjeta de cr\u00e9dito, brindan a los pasajeros [&hellip;]","twitter_image":"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg","twitter_creator":"@NITUmx","twitter_site":"@Arturo_Medina_G","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#article","isPartOf":{"@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b"},"headline":"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC","datePublished":"2022-09-15T04:51:28+00:00","dateModified":"2022-09-15T05:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/"},"wordCount":656,"commentCount":0,"publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg","keywords":["HSBC","HSBC VIVA","Juan Carlos Zuazua","tarjeta de cr\u00e9dito","Viva Aerobus"],"articleSection":["Aerol\u00edneas"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/","url":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/","name":"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC - Nitu - Noticias de la Industria Turistica","isPartOf":{"@id":"https:\/\/nitu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg","datePublished":"2022-09-15T04:51:28+00:00","dateModified":"2022-09-15T05:26:38+00:00","breadcrumb":{"@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#primaryimage","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2022\/09\/HSBC-VIVA-4.jpeg","width":1200,"height":675,"caption":"Viva Aerobus"},{"@type":"BreadcrumbList","@id":"https:\/\/nitu.mx\/index.php\/2022\/09\/14\/viva-aerobus-anuncia-mas-beneficios-a-sus-clientes-con-tarjeta-de-hsbc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/nitu.mx\/"},{"@type":"ListItem","position":2,"name":"Viva Aerobus anuncia m\u00e1s beneficios a sus clientes con tarjeta de HSBC"}]},{"@type":"WebSite","@id":"https:\/\/nitu.mx\/#website","url":"https:\/\/nitu.mx\/","name":"Nitu - Noticias de la Industria Turistica","description":"Noticias de la Industria Turistica","publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"alternateName":"Noticias de la Industria Turistica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitu.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":["Person","Organization"],"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc","name":"Arturo Medina","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","width":90,"height":90,"caption":"Arturo Medina"},"logo":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/"},"description":"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx","sameAs":["https:\/\/nitu.mx","https:\/\/www.facebook.com\/NITUmx\/","medinacancun","https:\/\/twitter.com\/@Arturo_Medina_G"]},{"@type":"Person","@id":"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/nitu.mx\/index.php\/author\/redaccion\/"}]}},"views":715,"_links":{"self":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/61366"}],"collection":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=61366"}],"version-history":[{"count":1,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/61366\/revisions"}],"predecessor-version":[{"id":61367,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/61366\/revisions\/61367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media\/61370"}],"wp:attachment":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=61366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=61366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=61366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}