{"id":24216,"date":"2018-09-06T00:17:54","date_gmt":"2018-09-06T05:17:54","guid":{"rendered":"https:\/\/www.dev.nitu.mx\/?p=24216"},"modified":"2018-09-06T00:37:11","modified_gmt":"2018-09-06T05:37:11","slug":"mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort","status":"publish","type":"post","link":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/","title":{"rendered":"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &#038; Resort\u201d"},"content":{"rendered":"<p>Con una inversi\u00f3n de 4,129 millones de pesos se alista la construcci\u00f3n del Desarrollo Tur\u00edstico Playa del Secreto Hotel &amp; Resort en el municipio de Solidaridad, de 2,139 cuartos, sobre un terreno costero de poco m\u00e1s de 13 hect\u00e1reas, a la altura del kil\u00f3metro 311+500 de la carretera Canc\u00fan-Tulum.<\/p>\n<p>De acuerdo a informaci\u00f3n de El Economista, el proyecto data del 2005, cuando por primera vez se le otorg\u00f3 la autorizaci\u00f3n condicionada para la construcci\u00f3n de todo un complejo de tres etapas e igual n\u00famero de hoteles, de los cuales s\u00f3lo se ha construido uno, denominado Valent\u00edn Imperial Riviera Maya de 540 habitaciones, en operaci\u00f3n desde el 2007.<\/p>\n<p>Dicha autorizaci\u00f3n de impacto ambiental tiene vigencia hasta el 2021, por lo que la firma promovente (Valent\u00edn Playa del Secreto) ech\u00f3 a andar los tr\u00e1mites para la construcci\u00f3n de las dos etapas complementarias del complejo, el cual consiste en dos hoteles.<\/p>\n<p>\u201cHotel 2 con 745 cuartos hoteleros y 75 viviendas para empleados, equivalente a 150 cuartos, y Hotel 3 con 704 cuartos; en total, el proyecto en todas sus etapas ser\u00e1 de 2,139 cuartos hoteleros\u201d, se\u00f1ala.<\/p>\n<p>La firma reconoce que \u201ccon base en la caracterizaci\u00f3n de flora en el predio del proyecto, la vegetaci\u00f3n se encuentra conformada de selva, manglar, duna costera, as\u00ed como cuerpos de agua, camino antiguo y el Hotel Valent\u00edn Imperial Riviera Maya actualmente en operaci\u00f3n\u201d; es decir, existe manglar, especie protegida por las leyes mexicanas dentro de los terrenos a impactar por este complejo.<\/p>\n<p>En cuanto al abastecimiento de agua se realizar\u00e1 la perforaci\u00f3n de seis nuevos pozos para obtener agua salobre, sumando un total de 12 pozos de aprovechamiento para los tres hoteles; se realizar\u00e1n adem\u00e1s dos nuevas desalinizadoras de osmosis inversa, una por cada hotel, que se ubicaran en el \u00e1rea de servicios, se a\u00f1ade en la descripci\u00f3n del proyecto.<\/p>\n<p>Se trata de uno de los proyectos m\u00e1s grandes y con la inversi\u00f3n m\u00e1s cuantiosa anunciada para la Riviera Maya en los \u00faltimos a\u00f1os, coment\u00f3 Wilberth Guti\u00e9rrez \u00c1lvarez, presidente de la Asociaci\u00f3n Mexicana de la Industria Inmobiliaria.<\/p>\n<p>Junto con la construcci\u00f3n de los parques y los hoteles del complejo Amikoo, cuya inversi\u00f3n asciende a 840 millones de d\u00f3lares, la Riviera Maya es uno de los destinos que mayor inversi\u00f3n hotelera estar\u00e1 captando entre el 2018 y el 2020, asegur\u00f3. (<a title=\"A fin de a\u00f1o, concluir\u00e1n primera fase de Amikoo\" href=\"https:\/\/www.dev.nitu.mx\/index.php\/2018\/04\/20\/a-fin-de-ano-concluiran-primera-fase-de-amikoo\/\" rel=\"bookmark\">A fin de a\u00f1o, concluir\u00e1n primera fase de Amikoo<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una inversi\u00f3n de 4,129 millones de pesos se alista la construcci\u00f3n del Desarrollo Tur\u00edstico Playa del Secreto Hotel &amp; Resort en el municipio de Solidaridad, de 2,139 cuartos, sobre un terreno costero de poco m\u00e1s de 13 hect\u00e1reas, a la altura del kil\u00f3metro 311+500 de la carretera Canc\u00fan-Tulum. De acuerdo a informaci\u00f3n de El [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":24237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,2],"tags":[12177,12178,12180,80,460,12179,142],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &amp; Resort\u201d - Nitu - Noticias de la Industria Turistica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &amp; Resort\u201d - Nitu - Noticias de la Industria Turistica\" \/>\n<meta name=\"twitter:description\" content=\"Con una inversi\u00f3n de 4,129 millones de pesos se alista la construcci\u00f3n del Desarrollo Tur\u00edstico Playa del Secreto Hotel &amp; Resort en el municipio de Solidaridad, de 2,139 cuartos, sobre un terreno costero de poco m\u00e1s de 13 hect\u00e1reas, a la altura del kil\u00f3metro 311+500 de la carretera Canc\u00fan-Tulum. De acuerdo a informaci\u00f3n de El [&hellip;]\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@NITUmx\" \/>\n<meta name=\"twitter:site\" content=\"@Arturo_Medina_G\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b\"},\"headline\":\"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &#038; Resort\u201d\",\"datePublished\":\"2018-09-06T05:17:54+00:00\",\"dateModified\":\"2018-09-06T05:37:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg\",\"keywords\":[\": \u201cPlaya del Secreto Hotel &amp; Resort\u201d\",\"carretera Canc\u00fan-Tulum\",\"presidente de la Asociaci\u00f3n Mexicana de la Industria Inmobiliaria\",\"Riviera Maya\",\"Solidaridad\",\"Valent\u00edn Imperial Riviera Maya\",\"Wilberth Guti\u00e9rrez \u00c1lvarez\"],\"articleSection\":[\"Destinos\",\"Hoteles\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/\",\"url\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/\",\"name\":\"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel & Resort\u201d - Nitu - Noticias de la Industria Turistica\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg\",\"datePublished\":\"2018-09-06T05:17:54+00:00\",\"dateModified\":\"2018-09-06T05:37:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg\",\"width\":850,\"height\":480,\"caption\":\"playa secreto hotel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/nitu.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &#038; Resort\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nitu.mx\/#website\",\"url\":\"https:\/\/nitu.mx\/\",\"name\":\"Nitu - Noticias de la Industria Turistica\",\"description\":\"Noticias de la Industria Turistica\",\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"alternateName\":\"Noticias de la Industria Turistica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nitu.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\",\"name\":\"Arturo Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"width\":90,\"height\":90,\"caption\":\"Arturo Medina\"},\"logo\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\"},\"description\":\"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx\",\"sameAs\":[\"https:\/\/nitu.mx\",\"https:\/\/www.facebook.com\/NITUmx\/\",\"medinacancun\",\"https:\/\/twitter.com\/@Arturo_Medina_G\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\/\/nitu.mx\/index.php\/author\/redaccion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel & Resort\u201d - Nitu - Noticias de la Industria Turistica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/","twitter_card":"summary_large_image","twitter_title":"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel & Resort\u201d - Nitu - Noticias de la Industria Turistica","twitter_description":"Con una inversi\u00f3n de 4,129 millones de pesos se alista la construcci\u00f3n del Desarrollo Tur\u00edstico Playa del Secreto Hotel &amp; Resort en el municipio de Solidaridad, de 2,139 cuartos, sobre un terreno costero de poco m\u00e1s de 13 hect\u00e1reas, a la altura del kil\u00f3metro 311+500 de la carretera Canc\u00fan-Tulum. De acuerdo a informaci\u00f3n de El [&hellip;]","twitter_image":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg","twitter_creator":"@NITUmx","twitter_site":"@Arturo_Medina_G","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#article","isPartOf":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b"},"headline":"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &#038; Resort\u201d","datePublished":"2018-09-06T05:17:54+00:00","dateModified":"2018-09-06T05:37:11+00:00","mainEntityOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg","keywords":[": \u201cPlaya del Secreto Hotel &amp; Resort\u201d","carretera Canc\u00fan-Tulum","presidente de la Asociaci\u00f3n Mexicana de la Industria Inmobiliaria","Riviera Maya","Solidaridad","Valent\u00edn Imperial Riviera Maya","Wilberth Guti\u00e9rrez \u00c1lvarez"],"articleSection":["Destinos","Hoteles"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/","url":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/","name":"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel & Resort\u201d - Nitu - Noticias de la Industria Turistica","isPartOf":{"@id":"https:\/\/nitu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg","datePublished":"2018-09-06T05:17:54+00:00","dateModified":"2018-09-06T05:37:11+00:00","breadcrumb":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#primaryimage","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/09\/playa-secreto-hotel.jpg","width":850,"height":480,"caption":"playa secreto hotel"},{"@type":"BreadcrumbList","@id":"https:\/\/nitu.mx\/index.php\/2018\/09\/06\/mas-de-4-mil-millones-de-pesos-se-invertiran-en-el-playa-del-secreto-hotel-resort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/nitu.mx\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 4 mil millones de pesos se invertir\u00e1n en el \u201cPlaya del Secreto Hotel &#038; Resort\u201d"}]},{"@type":"WebSite","@id":"https:\/\/nitu.mx\/#website","url":"https:\/\/nitu.mx\/","name":"Nitu - Noticias de la Industria Turistica","description":"Noticias de la Industria Turistica","publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"alternateName":"Noticias de la Industria Turistica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitu.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":["Person","Organization"],"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc","name":"Arturo Medina","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","width":90,"height":90,"caption":"Arturo Medina"},"logo":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/"},"description":"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx","sameAs":["https:\/\/nitu.mx","https:\/\/www.facebook.com\/NITUmx\/","medinacancun","https:\/\/twitter.com\/@Arturo_Medina_G"]},{"@type":"Person","@id":"https:\/\/nitu.mx\/#\/schema\/person\/4a28fe9bd65924f7c90623773daf1b0b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5dd011c8ccfc5cd7e4c81e42252aab38?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/nitu.mx\/index.php\/author\/redaccion\/"}]}},"views":270,"_links":{"self":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/24216"}],"collection":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=24216"}],"version-history":[{"count":3,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/24216\/revisions"}],"predecessor-version":[{"id":24247,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/24216\/revisions\/24247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media\/24237"}],"wp:attachment":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=24216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=24216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=24216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}