{"id":19020,"date":"2018-04-01T23:03:13","date_gmt":"2018-04-02T04:03:13","guid":{"rendered":"http:\/\/www.dev.nitu.mx\/?p=19020"},"modified":"2018-04-02T00:05:23","modified_gmt":"2018-04-02T05:05:23","slug":"ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales","status":"publish","type":"post","link":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/","title":{"rendered":"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d"},"content":{"rendered":"<p>El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las llamadas plataformas colaborativas de rentas vacacionales, que en un inicio fueron incentivadas en Palma de Mallorca, Barcelona y otros centros vacacionales.<\/p>\n<p>Rosell\u00f3 encabeza la asociaci\u00f3n que aglutina a las cadenas espa\u00f1olas m\u00e1s importantes, que tienen presencia en Canc\u00fan en particular, pero en general en todo el Caribe.<\/p>\n<p>El espa\u00f1ol se\u00f1al\u00f3 que en su pa\u00eds, cuando inici\u00f3 el fen\u00f3meno de plataformas de rentas de casas para vacaciones como Airbnb o HomeAway, en Barcelona, Canarias, Palma de Mallorca, primero las incentivaron, pero ante los problemas que han surgido ahora han comenzado a regularizarlos de forma m\u00e1s rigurosa.<\/p>\n<p>\u201cHay graves problemas que se fueron dando, desde la inseguridad, que es el principal problema, hasta la saturaci\u00f3n del destino, porque sin datos, sin informaci\u00f3n desconoces cu\u00e1ntos turistas se pueden recibir. Adem\u00e1s las rentas se vuelven m\u00e1s caras e impagables para los ciudadanos, desplaz\u00e1ndolos de los sitios visitados a la periferia provocando mayores problemas en la comunidad\u201d, detall\u00f3.<\/p>\n<p>Explic\u00f3 que \u201cLo que es doloroso (en el caso del Caribe Mexicano) es que haya fallecido en un departamento en Tulum, una familia (Sharp de EU por gases t\u00f3xicos). Entonces el tema principal es el de la seguridad, salubridad y falta de control. No hablamos de una seguridad ciudadana, sino de d\u00f3nde se hospedan\u201d.\u00a0<a title=\"Hoteleros: Se acab\u00f3 el tiempo para regular a plataformas de rentas vacacionales\" href=\"http:\/\/www.dev.nitu.mx\/index.php\/2018\/03\/27\/hoteleros-se-acabo-el-tiempo-para-regular-a-plataformas-de-rentas-vacacionales\/\" rel=\"bookmark\">(Hoteleros: Se acab\u00f3 el tiempo para regular a plataformas de rentas vacacionales<\/a>).<\/p>\n<p>Resalt\u00f3 que: \u201cEl principal punto es que esas plataformas tienen que garantizar como lo hacen los hoteleros, su seguridad, las normas urban\u00edsticas en los pasillos, las habitaciones, todo el hotel. De igual forma deben cumplir con la misma normativa\u201d.<\/p>\n<p>Incentiv\u00f3 a los ciudadanos que rentan a ver por el bien com\u00fan, a pensar en las afectaciones a todo el destino, el incremento de los precios, el destino de los desechos, y mucho m\u00e1s, que al final son contraproducentes para todo el destino en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las llamadas plataformas colaborativas de rentas vacacionales, que en un inicio fueron incentivadas en Palma de Mallorca, Barcelona y otros centros vacacionales. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,6],"tags":[3113,43,83,1213,7025,5770,5910,7026,4878],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d - Nitu - Noticias de la Industria Turistica<\/title>\n<meta name=\"description\" content=\"El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las plataformas de rentas vacacionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d - Nitu - Noticias de la Industria Turistica\" \/>\n<meta name=\"twitter:description\" content=\"El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las plataformas de rentas vacacionales.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@NITUmx\" \/>\n<meta name=\"twitter:site\" content=\"@Arturo_Medina_G\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandra Moncisbays\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/\"},\"author\":{\"name\":\"Alejandra Moncisbays\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/2ecd887b19dfd3382d1f14fc5acf24a8\"},\"headline\":\"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d\",\"datePublished\":\"2018-04-02T04:03:13+00:00\",\"dateModified\":\"2018-04-02T05:05:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg\",\"keywords\":[\"Barcelona\",\"Canc\u00fan\",\"Caribe mexicano\",\"Espa\u00f1a\",\"Inverotel\",\"Palma de Mallorca\",\"plataformas\",\"Ram\u00f3n Rosell\u00f3\",\"rentas vacacionales\"],\"articleSection\":[\"Hoteles\",\"M\u00e9xico\"],\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/\",\"url\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/\",\"name\":\"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d - Nitu - Noticias de la Industria Turistica\",\"isPartOf\":{\"@id\":\"https:\/\/nitu.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg\",\"datePublished\":\"2018-04-02T04:03:13+00:00\",\"dateModified\":\"2018-04-02T05:05:23+00:00\",\"description\":\"El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las plataformas de rentas vacacionales.\",\"breadcrumb\":{\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg\",\"width\":850,\"height\":480,\"caption\":\"Ram\u00f3n Rosell\u00f3 tiempo compartido rentas vacacionales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/nitu.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nitu.mx\/#website\",\"url\":\"https:\/\/nitu.mx\/\",\"name\":\"Nitu - Noticias de la Industria Turistica\",\"description\":\"Noticias de la Industria Turistica\",\"publisher\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\"},\"alternateName\":\"Noticias de la Industria Turistica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nitu.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc\",\"name\":\"Arturo Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"contentUrl\":\"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg\",\"width\":90,\"height\":90,\"caption\":\"Arturo Medina\"},\"logo\":{\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\"},\"description\":\"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx\",\"sameAs\":[\"https:\/\/nitu.mx\",\"https:\/\/www.facebook.com\/NITUmx\/\",\"medinacancun\",\"https:\/\/twitter.com\/@Arturo_Medina_G\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/2ecd887b19dfd3382d1f14fc5acf24a8\",\"name\":\"Alejandra Moncisbays\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/nitu.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e74f7af0be172b7804dacfd0bfbef787?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e74f7af0be172b7804dacfd0bfbef787?s=96&d=mm&r=g\",\"caption\":\"Alejandra Moncisbays\"},\"description\":\"Curs\u00e9 la carrera de Periodismo y Comunicaci\u00f3n en la Facultad de Estudios Profesionales Acatl\u00e1n. Vivo en Canc\u00fan desde hace 24 a\u00f1os. Fui reportera de La Tarde de Canc\u00fan, y Novedades de Quintana Roo, colabor\u00e9 en TVCUN, edit\u00e9 Cancun\u00edssimo y colabor\u00e9 en las revistas Latitud21, entre otras, con principal enfoque en los sectores empresarial y tur\u00edstico. Desde hace varios a\u00f1os soy Agente de Seguros con c\u00e9dula de la Comisi\u00f3n Nacional de Seguros y Fianzas. Actualmente, me desarrollo en los \u00e1mbitos del periodismo y el sector asegurador.\",\"sameAs\":[\"https:\/\/nitu.mx\"],\"url\":\"https:\/\/nitu.mx\/index.php\/author\/alejandra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d - Nitu - Noticias de la Industria Turistica","description":"El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las plataformas de rentas vacacionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/","twitter_card":"summary_large_image","twitter_title":"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d - Nitu - Noticias de la Industria Turistica","twitter_description":"El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las plataformas de rentas vacacionales.","twitter_image":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg","twitter_creator":"@NITUmx","twitter_site":"@Arturo_Medina_G","twitter_misc":{"Escrito por":"Alejandra Moncisbays","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#article","isPartOf":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/"},"author":{"name":"Alejandra Moncisbays","@id":"https:\/\/nitu.mx\/#\/schema\/person\/2ecd887b19dfd3382d1f14fc5acf24a8"},"headline":"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d","datePublished":"2018-04-02T04:03:13+00:00","dateModified":"2018-04-02T05:05:23+00:00","mainEntityOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg","keywords":["Barcelona","Canc\u00fan","Caribe mexicano","Espa\u00f1a","Inverotel","Palma de Mallorca","plataformas","Ram\u00f3n Rosell\u00f3","rentas vacacionales"],"articleSection":["Hoteles","M\u00e9xico"],"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/","url":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/","name":"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d - Nitu - Noticias de la Industria Turistica","isPartOf":{"@id":"https:\/\/nitu.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage"},"image":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg","datePublished":"2018-04-02T04:03:13+00:00","dateModified":"2018-04-02T05:05:23+00:00","description":"El gerente de Inverotel, Ram\u00f3n Rosell\u00f3, alert\u00f3 a la comunidad en general y a las autoridades del Caribe Mexicano, respecto a los aspectos negativos que se han dado en Espa\u00f1a, en torno a las plataformas de rentas vacacionales.","breadcrumb":{"@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#primaryimage","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2018\/04\/rentas-vacacionales.jpg","width":850,"height":480,"caption":"Ram\u00f3n Rosell\u00f3 tiempo compartido rentas vacacionales"},{"@type":"BreadcrumbList","@id":"https:\/\/nitu.mx\/index.php\/2018\/04\/01\/ramon-rosello-alerta-respecto-a-los-supuestos-beneficios-de-las-plataformas-de-rentas-vacacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/nitu.mx\/"},{"@type":"ListItem","position":2,"name":"Ram\u00f3n Rosell\u00f3 alerta respecto a \u201clos supuestos beneficios de las plataformas de rentas vacacionales\u201d"}]},{"@type":"WebSite","@id":"https:\/\/nitu.mx\/#website","url":"https:\/\/nitu.mx\/","name":"Nitu - Noticias de la Industria Turistica","description":"Noticias de la Industria Turistica","publisher":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc"},"alternateName":"Noticias de la Industria Turistica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitu.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":["Person","Organization"],"@id":"https:\/\/nitu.mx\/#\/schema\/person\/ae7a53426417292d3dd07b45a33e01bc","name":"Arturo Medina","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","contentUrl":"https:\/\/nitu.mx\/wp-content\/uploads\/2024\/04\/4A315622-1904-4D5C-B022-878CDC840E04-90x90-1.jpeg","width":90,"height":90,"caption":"Arturo Medina"},"logo":{"@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/"},"description":"Director NITU.mx, Egresado de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda. Periodista y analista especializado en turismo desde hace 35 a\u00f1os, radicado en Canc\u00fan Q.Roo. arturo@nitu.mx","sameAs":["https:\/\/nitu.mx","https:\/\/www.facebook.com\/NITUmx\/","medinacancun","https:\/\/twitter.com\/@Arturo_Medina_G"]},{"@type":"Person","@id":"https:\/\/nitu.mx\/#\/schema\/person\/2ecd887b19dfd3382d1f14fc5acf24a8","name":"Alejandra Moncisbays","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/nitu.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e74f7af0be172b7804dacfd0bfbef787?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e74f7af0be172b7804dacfd0bfbef787?s=96&d=mm&r=g","caption":"Alejandra Moncisbays"},"description":"Curs\u00e9 la carrera de Periodismo y Comunicaci\u00f3n en la Facultad de Estudios Profesionales Acatl\u00e1n. Vivo en Canc\u00fan desde hace 24 a\u00f1os. Fui reportera de La Tarde de Canc\u00fan, y Novedades de Quintana Roo, colabor\u00e9 en TVCUN, edit\u00e9 Cancun\u00edssimo y colabor\u00e9 en las revistas Latitud21, entre otras, con principal enfoque en los sectores empresarial y tur\u00edstico. Desde hace varios a\u00f1os soy Agente de Seguros con c\u00e9dula de la Comisi\u00f3n Nacional de Seguros y Fianzas. Actualmente, me desarrollo en los \u00e1mbitos del periodismo y el sector asegurador.","sameAs":["https:\/\/nitu.mx"],"url":"https:\/\/nitu.mx\/index.php\/author\/alejandra\/"}]}},"views":299,"_links":{"self":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/19020"}],"collection":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19020"}],"version-history":[{"count":3,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/19020\/revisions"}],"predecessor-version":[{"id":19030,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/posts\/19020\/revisions\/19030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media\/19029"}],"wp:attachment":[{"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nitu.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}